{"id":6530,"date":"2025-04-24T08:09:41","date_gmt":"2025-04-24T13:09:41","guid":{"rendered":"https:\/\/clinaltec.com\/?page_id=6530"},"modified":"2026-04-17T10:02:57","modified_gmt":"2026-04-17T15:02:57","slug":"estados-financieros-clinaltec","status":"publish","type":"page","link":"https:\/\/clinaltec.com\/en\/estados-financieros-clinaltec\/","title":{"rendered":"Financial Statements CLINALTEC"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"6530\" class=\"elementor elementor-6530\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cf7904c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cf7904c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40227293\" data-id=\"40227293\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-200efc5b elementor-widget elementor-widget-heading\" data-id=\"200efc5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CLINICA INTERNACIONAL DE ALTA TECNOLOGIA SAS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59f40811 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59f40811\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1b7dcecd\" data-id=\"1b7dcecd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1cce8673 elementor-widget elementor-widget-heading\" data-id=\"1cce8673\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Financial Statements Year 2025<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46e05e1\" data-id=\"46e05e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3afdbb0f elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"3afdbb0f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/clinaltec.com\/wp-content\/uploads\/2025\/02\/PC-TIC-01-POLITICA-DE-TRATAMIENTO-DE-DATOS-PERSONALES.pdf\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download here<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d841180 e-flex e-con-boxed e-con e-parent\" data-id=\"d841180\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b956e83 elementor-widget elementor-widget-text-editor\" data-id=\"b956e83\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"_df_book df-lite\" id=\"df_7345\"  _slug=\"estados-financieros-2025\" data-title=\"estados-financieros-2025\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" nowprocket type=\"application\/javascript\">window.option_df_7345 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"enableDownload\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"source\":\"https:\\\/\\\/clinaltec.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ESTADOS-FINANCIEROS-CLINALTEC-2025.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e348994 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e348994\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3759e4d\" data-id=\"3759e4d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ddb75c elementor-widget elementor-widget-heading\" data-id=\"3ddb75c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">STATEMENT OF FINANCIAL POSITION\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2579ad\" data-id=\"a2579ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c8ed82b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"c8ed82b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"https:\/\/clinaltec.com\/wp-content\/uploads\/2025\/02\/PC-TIC-01-POLITICA-DE-TRATAMIENTO-DE-DATOS-PERSONALES.pdf\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Download here<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e043123 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e043123\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60a5a85b\" data-id=\"60a5a85b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-664daf13 elementor-widget elementor-widget-text-editor\" data-id=\"664daf13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><div class=\"_df_book df-lite\" id=\"df_6534\"  _slug=\"estado-de-situacion-financiera\" data-title=\"estado-de-situacion-financiera\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" nowprocket type=\"application\/javascript\">window.option_df_6534 = {\"outline\":[],\"viewerType\":\"slider\",\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"enableDownload\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"maxTextureSize\":\"2048\",\"source\":\"https:\\\/\\\/clinaltec.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/ESTADOS-FINANCIEROS-CLINALTEC-2024-PARA-PUBLICAR.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CLINICA INTERNACIONAL DE ALTA TECNOLOGIA SAS FINANCIAL STATEMENTS YEAR 2025 Download here STATEMENT OF FINANCIAL POSITION Download here<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-6530","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/pages\/6530","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/comments?post=6530"}],"version-history":[{"count":12,"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/pages\/6530\/revisions"}],"predecessor-version":[{"id":7353,"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/pages\/6530\/revisions\/7353"}],"wp:attachment":[{"href":"https:\/\/clinaltec.com\/en\/wp-json\/wp\/v2\/media?parent=6530"}],"curies":[{"name":"WordPress","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}